{"id":1746,"date":"2025-06-24T08:43:42","date_gmt":"2025-06-24T01:43:42","guid":{"rendered":"https:\/\/forthen-indonesia.com\/?post_type=product&#038;p=1746"},"modified":"2025-06-24T08:43:42","modified_gmt":"2025-06-24T01:43:42","slug":"grooved-end-gate-valve","status":"publish","type":"product","link":"https:\/\/forthen-indonesia.com\/id\/produk\/grooved-end-gate-valve\/","title":{"rendered":"Grooved End Gate Valve"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1743,"comment_status":"open","ping_status":"closed","template":"","meta":[],"material":[],"product_brand":[67],"product_cat":[55],"product_tag":[],"class_list":{"0":"post-1746","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-apc-valve","7":"product_cat-valve","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grooved End Gate Valve - Forthen Indonesia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forthen-indonesia.com\/id\/produk\/grooved-end-gate-valve\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grooved End Gate Valve - Forthen Indonesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forthen-indonesia.com\/id\/produk\/grooved-end-gate-valve\/\" \/>\n<meta property=\"og:site_name\" content=\"Forthen Indonesia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/06\/Grooved-End-Gate-Valve.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimasi waktu membaca\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 menit\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/\",\"url\":\"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/\",\"name\":\"Grooved End Gate Valve - Forthen Indonesia\",\"isPartOf\":{\"@id\":\"https:\/\/forthen-indonesia.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/06\/Grooved-End-Gate-Valve.png\",\"datePublished\":\"2025-06-24T01:43:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#primaryimage\",\"url\":\"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/06\/Grooved-End-Gate-Valve.png\",\"contentUrl\":\"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/06\/Grooved-End-Gate-Valve.png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/forthen-indonesia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/forthen-indonesia.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grooved End Gate Valve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/forthen-indonesia.com\/#website\",\"url\":\"https:\/\/forthen-indonesia.com\/\",\"name\":\"Forthen Indonesia\",\"description\":\"Empower your Excellence\",\"publisher\":{\"@id\":\"https:\/\/forthen-indonesia.com\/#organization\"},\"alternateName\":\"PT Forthen Indonesia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/forthen-indonesia.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/forthen-indonesia.com\/#organization\",\"name\":\"Forthen Indonesia\",\"url\":\"https:\/\/forthen-indonesia.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\/\/forthen-indonesia.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/logo-forthen-indonesia.png\",\"contentUrl\":\"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/logo-forthen-indonesia.png\",\"width\":396,\"height\":136,\"caption\":\"Forthen Indonesia\"},\"image\":{\"@id\":\"https:\/\/forthen-indonesia.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grooved End Gate Valve - Forthen Indonesia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forthen-indonesia.com\/id\/produk\/grooved-end-gate-valve\/","og_locale":"id_ID","og_type":"article","og_title":"Grooved End Gate Valve - Forthen Indonesia","og_url":"https:\/\/forthen-indonesia.com\/id\/produk\/grooved-end-gate-valve\/","og_site_name":"Forthen Indonesia","og_image":[{"width":1000,"height":1000,"url":"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/06\/Grooved-End-Gate-Valve.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimasi waktu membaca":"1 menit"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/","url":"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/","name":"Grooved End Gate Valve - Forthen Indonesia","isPartOf":{"@id":"https:\/\/forthen-indonesia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#primaryimage"},"image":{"@id":"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#primaryimage"},"thumbnailUrl":"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/06\/Grooved-End-Gate-Valve.png","datePublished":"2025-06-24T01:43:42+00:00","breadcrumb":{"@id":"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/"]}]},{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#primaryimage","url":"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/06\/Grooved-End-Gate-Valve.png","contentUrl":"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/06\/Grooved-End-Gate-Valve.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/forthen-indonesia.com\/product\/grooved-end-gate-valve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forthen-indonesia.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/forthen-indonesia.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Grooved End Gate Valve"}]},{"@type":"WebSite","@id":"https:\/\/forthen-indonesia.com\/#website","url":"https:\/\/forthen-indonesia.com\/","name":"Forthen Indonesia","description":"Mitra Andal Anda dalam Keunggulan Konstruksi","publisher":{"@id":"https:\/\/forthen-indonesia.com\/#organization"},"alternateName":"PT Forthen Indonesia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forthen-indonesia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/forthen-indonesia.com\/#organization","name":"Forthen Indonesia","url":"https:\/\/forthen-indonesia.com\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/forthen-indonesia.com\/#\/schema\/logo\/image\/","url":"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/logo-forthen-indonesia.png","contentUrl":"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/logo-forthen-indonesia.png","width":396,"height":136,"caption":"Forthen Indonesia"},"image":{"@id":"https:\/\/forthen-indonesia.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/product\/1746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/comments?post=1746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/media\/1743"}],"wp:attachment":[{"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/media?parent=1746"}],"wp:term":[{"taxonomy":"material","embeddable":true,"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/material?post=1746"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/product_brand?post=1746"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/product_cat?post=1746"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/product_tag?post=1746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}