{"id":39,"count":0,"description":"","link":"https:\/\/forthen-indonesia.com\/id\/material\/steel\/","name":"Steel","slug":"steel","taxonomy":"material","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Steel Archives - Forthen Indonesia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forthen-indonesia.com\/id\/material\/steel\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steel Archives - Forthen Indonesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forthen-indonesia.com\/id\/material\/steel\/\" \/>\n<meta property=\"og:site_name\" content=\"Forthen Indonesia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/james-sullivan-ESZRBtkQ_f8-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/forthen-indonesia.com\/material\/steel\/\",\"url\":\"https:\/\/forthen-indonesia.com\/material\/steel\/\",\"name\":\"Steel Archives - Forthen Indonesia\",\"isPartOf\":{\"@id\":\"https:\/\/forthen-indonesia.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/forthen-indonesia.com\/material\/steel\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/forthen-indonesia.com\/material\/steel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/forthen-indonesia.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/forthen-indonesia.com\/#website\",\"url\":\"https:\/\/forthen-indonesia.com\/\",\"name\":\"Forthen Indonesia\",\"description\":\"Empower your Excellence\",\"publisher\":{\"@id\":\"https:\/\/forthen-indonesia.com\/#organization\"},\"alternateName\":\"PT Forthen Indonesia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/forthen-indonesia.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/forthen-indonesia.com\/#organization\",\"name\":\"Forthen Indonesia\",\"url\":\"https:\/\/forthen-indonesia.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\/\/forthen-indonesia.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/logo-forthen-indonesia.png\",\"contentUrl\":\"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/logo-forthen-indonesia.png\",\"width\":396,\"height\":136,\"caption\":\"Forthen Indonesia\"},\"image\":{\"@id\":\"https:\/\/forthen-indonesia.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Steel Archives - Forthen Indonesia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forthen-indonesia.com\/id\/material\/steel\/","og_locale":"id_ID","og_type":"article","og_title":"Steel Archives - Forthen Indonesia","og_url":"https:\/\/forthen-indonesia.com\/id\/material\/steel\/","og_site_name":"Forthen Indonesia","og_image":[{"width":1000,"height":1250,"url":"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/james-sullivan-ESZRBtkQ_f8-unsplash.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/forthen-indonesia.com\/material\/steel\/","url":"https:\/\/forthen-indonesia.com\/material\/steel\/","name":"Steel Archives - Forthen Indonesia","isPartOf":{"@id":"https:\/\/forthen-indonesia.com\/#website"},"breadcrumb":{"@id":"https:\/\/forthen-indonesia.com\/material\/steel\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/forthen-indonesia.com\/material\/steel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forthen-indonesia.com\/"},{"@type":"ListItem","position":2,"name":"Steel"}]},{"@type":"WebSite","@id":"https:\/\/forthen-indonesia.com\/#website","url":"https:\/\/forthen-indonesia.com\/","name":"Forthen Indonesia","description":"Mitra Andal Anda dalam Keunggulan Konstruksi","publisher":{"@id":"https:\/\/forthen-indonesia.com\/#organization"},"alternateName":"PT Forthen Indonesia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forthen-indonesia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/forthen-indonesia.com\/#organization","name":"Forthen Indonesia","url":"https:\/\/forthen-indonesia.com\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/forthen-indonesia.com\/#\/schema\/logo\/image\/","url":"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/logo-forthen-indonesia.png","contentUrl":"https:\/\/forthen-indonesia.com\/wp-content\/uploads\/2025\/03\/logo-forthen-indonesia.png","width":396,"height":136,"caption":"Forthen Indonesia"},"image":{"@id":"https:\/\/forthen-indonesia.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/material\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/material"}],"about":[{"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/taxonomies\/material"}],"wp:post_type":[{"href":"https:\/\/forthen-indonesia.com\/id\/wp-json\/wp\/v2\/product?material=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}